{"id":43083,"date":"2018-05-30T08:53:45","date_gmt":"2018-05-30T06:53:45","guid":{"rendered":"https:\/\/escoles.fundesplai.org\/sin-categorizar\/que-son-las-bressol-de-verano\/"},"modified":"2023-06-16T08:56:47","modified_gmt":"2023-06-16T06:56:47","slug":"que-son-las-bressol-de-verano","status":"publish","type":"post","link":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/","title":{"rendered":"\u00bfQu\u00e9 son las Bressol de verano?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.17.1&#8243; z_index_tablet=\u00bb500&#8243; text_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_text_shadow_blur_strength_tablet=\u00bb1px\u00bb link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_2_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_2_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_2_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_3_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_3_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_3_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_4_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_4_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_4_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_5_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_5_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_5_text_shadow_blur_strength_tablet=\u00bb1px\u00bb header_6_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_6_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_6_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Las Bressol de Verano<\/strong> son una oportunidad para que los ni\u00f1os\/as de <strong>0 a 3 a\u00f1os<\/strong> disfruten de un espacio de tiempo libre a partir de diferentes propuestas de actividades para favorecer su crecimiento como persona durante el verano.<\/p>\n<p>Son <strong>los casales de verano de la peque\u00f1a infancia,<\/strong> con las actividades, din\u00e1micas, ritmos y educadores\/as necesarias para contribuir a su desarrollo.<\/p>\n<div>Cada vez hay m\u00e1s Ayuntamientos, AFAs y AMPAs de las escoles bressol que organizan <a href=\"https:\/\/escoles.fundesplai.org\/bressol-destiu\/\">Bressols de Verano<\/a> como una apuesta para ofrecer<strong> a los ni\u00f1os y ni\u00f1as un tiempo de ocio educativo de calidad y a las familias un espacio de calidad de conciliaci\u00f3n<\/strong> entre la vida laboral y familiar.<\/div>\n<div> <\/div>\n<div>El verano nos ofrece la posibilidad de profundizar en la exploraci\u00f3n del mundo, la experimentaci\u00f3n con diversos materiales, el descubrimiento del espacio exterior, el jard\u00edn, las plantas, los olores,&#8230; y tambi\u00e9n el placer de <a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/10-juegos-de-agua-para-la-escuela-infantil\/\">jugar y experimentar con el agua<\/a>, la reina del verano.<\/div>\n<div> <\/div>\n<h3>Los objetivos de las Bressol de Verano<\/h3>\n<ul>\n<li>Favorecer el desarrollo integral de los ni\u00f1os y ni\u00f1as<\/li>\n<li>Ofrecer un servicio de conciliaci\u00f3n familiar y laboral<\/li>\n<li>\n<div>Seguir la misma l\u00ednea y metodolog\u00eda educativa de la escola bressol<\/div>\n<\/li>\n<li>\n<div>Ofrecer diferentes ambientes (aulas y jard\u00edn) con propuestas de juego adecuadas a todas las edades<\/div>\n<\/li>\n<li>Favorecer el juego en el exterior y el contacto con la naturaleza<\/li>\n<li>\n<div>Asegurar un espacio acogedor y un ambiente tranquilo<\/div>\n<\/li>\n<li>\n<div>Potenciar la autonom\u00eda del ni\u00f1o\/a y la adquisici\u00f3n de h\u00e1bitos de higiene, alimentaci\u00f3n y descanso a partir de la actividad de la vida cotidiana<\/div>\n<\/li>\n<li>\n<div>Garantizar la comunicaci\u00f3n y la relaci\u00f3n con las familias<\/div>\n<\/li>\n<li>\u00a1Pasarlo muy bien durante el verano!<\/li>\n<\/ul>\n<p>[bctt tweet=\u00bbLes Bressol d&#8217;Estiu s\u00f3n els casals d&#8217;estiu per la Petita Inf\u00e0ncia i permeten que els infants de 0 a 3 anys gaudeixin del lleure a l&#8217;estiu amb molt de joc, aigua, experimentaci\u00f3 i diversi\u00f3! #casalestiu #bressol\u00bb username=\u00bbFundesplai\u00bb]<\/p>\n<h3>Naturaleza, agua y mucha experimentaci\u00f3n<\/h3>\n<p>Las actividades est\u00e1n basadas en los intereses y capacidades de los ni\u00f1os, integrando las diferentes \u00e1reas de aprendizaje y favoreciendo el juego como herramienta pedag\u00f3gica.<\/p>\n<p>Adem\u00e1s, <strong>potenciamos las actividades de exterior, la experimentaci\u00f3n con el agua y el contacto con la naturaleza<\/strong>, ya que tiene muchos efectos beneficiosos para la salud, tanto f\u00edsica como psicol\u00f3gica y favorece el desarrollo equilibrado de los ni\u00f1os\/as, tal y como explican autores como <a href=\"http:\/\/richardlouv.com\/about\/\">Richard Louv<\/a> (autor de <em>The Last Child in the Woords<\/em> ), <a href=\"http:\/\/educarenverde.blogspot.com.es\/\">Heike Freire<\/a> (autora de <em>Educar en Verde<\/em> ), o Angela J. Hanscom en su libro <a href=\"http:\/\/www.angleeditorial.com\/equilibrats-i-descalos-727\"><em>Equilibrados y descalzos<\/em><\/a> .<\/p>\n<p>Es muy importante que <strong>el proyecto de las Bressol de Verano d\u00e9 continuidad a la l\u00ednea pedag\u00f3gica de la escuela<\/strong> y que la entidad que gestiona el proyecto est\u00e9 coordinada con el equipo docente del centro y el AMPA o AFA.<\/p>\n<p>Algunas de las actividades que hacemos:<\/p>\n<h4>Jugamos y aprendemos con el agua<\/h4>\n<p><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/Juguem-amb-aigua-bressol.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6565 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/Juguem-amb-aigua-bressol.jpg\" alt=\"jugar agua Bressol Verano fundesplai\" width=\"800\" height=\"350\"><\/a><\/p>\n<h4>Estamos en contacto con la naturaleza<\/h4>\n<p><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/natura_bressol_estiu.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6569 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/natura_bressol_estiu.jpg\" alt=\"nautra bressol verano\" width=\"800\" height=\"350\"><\/a><\/p>\n<h4>Descubrimos con el cuerpo<\/h4>\n<p><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/cami_sensorial_bressol.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6566 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/cami_sensorial_bressol.jpg\" alt=\"camino sensorial Bressol\" width=\"800\" height=\"350\"><\/a><\/p>\n<h4>Disfrutamos con los cuentos<\/h4>\n<p><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/contes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6567 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/contes.jpg\" alt=\"cuentos bressols\" width=\"800\" height=\"350\"><\/a><\/p>\n<h4>Jugamos en grupo<\/h4>\n<p><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/Joc_grup.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6568 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/Joc_grup.jpg\" alt=\"juego simb\u00f3lico escolal bressol\" width=\"800\" height=\"350\"><\/a><\/p>\n<h4>Experimentamos con distintos materiales<\/h4>\n<h4><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/experimentacio_materials.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6570 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/experimentacio_materials.jpg\" alt=\"experimentaci\u00f3n juego heur\u00edstico\" width=\"800\" height=\"350\"><\/a><\/h4>\n<h4>Nos divertimos creando y experimentando con el color<\/h4>\n<p><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/Pintem_bressol_estiu.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6571 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/Pintem_bressol_estiu.jpg\" alt=\"Pintura bressol verano\" width=\"800\" height=\"350\"><\/a><\/p>\n<h4>Disfrutamos del juego al aire libre<\/h4>\n<p><a href=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/peus_aigua_sorra2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6574 aligncenter\" src=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/peus_aigua_sorra2.jpg\" alt=\"Experimentar pies agua bressol\" width=\"800\" height=\"350\"><\/a><\/p>\n<div class='et-box et-shadow'>\n\t\t\t\t\t<div class='et-box-content'>Organizamos Bressols de Verano y nos encargamos de todo: desde el proyecto educativo y los monitores\/as hasta la preparaci\u00f3n de la documentaci\u00f3n, los tr\u00e1mites, las inscripciones, etc. Consultad nuestra <a href=\"https:\/\/escoles.fundesplai.org\/bressol-destiu\/\">propuesta de actividades para las Bressols de Verano de este a\u00f1o<\/a>.<\/p>\n<p>Pod\u00e9is llamar al <strong>93 474 74 65<\/strong> o <a href=\"https:\/\/escoles.fundesplai.org\/es\/contacta\/\">contactar<\/a> y os organizamos una Bressol de verano a medida.<\/div><\/div>\n<p style=\"text-align: center;\"><strong>\u00a1Si te ha gustado este art\u00edculo comparte en las redes!<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Bressol de Verano son los casles de verano para la Peque\u00f1a Infancia, permiten a los ni\u00f1os\/as de 0 a 3 disfrutar del ocio a trav\u00e9s de los juegos, del agua y de la experimentaci\u00f3n. \u00a1Disfrutemos del verano!<\/p>\n","protected":false},"author":3,"featured_media":42802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[302],"tags":[673,275,486,487,585,441,586],"ppma_author":[809],"class_list":["post-43083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pequena-infancia","tag-0-3-es","tag-actividades","tag-casal-es","tag-casal-de-verano","tag-escuela-infantil","tag-juego","tag-pequena-infancia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 son las Bressol de verano? - Fundesplai M\u00f3n Escolar<\/title>\n<meta name=\"description\" content=\"Las Bressol de Verano son los casales de verano para la Peque\u00f1a Infancia, \u00a1permiten a los ni\u00f1os\/as de 0 a 3 disfrutar del ocio en verano!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 son las Bressol de verano? - Fundesplai M\u00f3n Escolar\" \/>\n<meta property=\"og:description\" content=\"Las Bressol de Verano son los casales de verano para la Peque\u00f1a Infancia, \u00a1permiten a los ni\u00f1os\/as de 0 a 3 disfrutar del ocio en verano!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundesplai M\u00f3n Escolar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-30T06:53:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-16T06:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/BRESSOLS_ESTIU_Fundesplai-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cespinosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fundesplai\" \/>\n<meta name=\"twitter:site\" content=\"@fundesplai\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cespinosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/\"},\"author\":{\"name\":\"cespinosa\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/76811d1ba58c8af329733060a9b10f67\"},\"headline\":\"\u00bfQu\u00e9 son las Bressol de verano?\",\"datePublished\":\"2018-05-30T06:53:45+00:00\",\"dateModified\":\"2023-06-16T06:56:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/\"},\"wordCount\":929,\"publisher\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/BRESSOLS_ESTIU_Fundesplai-1.jpg\",\"keywords\":[\"0-3\",\"actividades\",\"casal\",\"casal de verano\",\"escuela infantil\",\"juego\",\"peque\u00f1a infancia\"],\"articleSection\":[\"Peque\u00f1a infancia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/\",\"name\":\"\u00bfQu\u00e9 son las Bressol de verano? - Fundesplai M\u00f3n Escolar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/BRESSOLS_ESTIU_Fundesplai-1.jpg\",\"datePublished\":\"2018-05-30T06:53:45+00:00\",\"dateModified\":\"2023-06-16T06:56:47+00:00\",\"description\":\"Las Bressol de Verano son los casales de verano para la Peque\u00f1a Infancia, \u00a1permiten a los ni\u00f1os\\\/as de 0 a 3 disfrutar del ocio en verano!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/BRESSOLS_ESTIU_Fundesplai-1.jpg\",\"contentUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/BRESSOLS_ESTIU_Fundesplai-1.jpg\",\"width\":1888,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/que-son-las-bressol-de-verano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Peque\u00f1a infancia\",\"item\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/pequena-infancia\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00bfQu\u00e9 son las Bressol de verano?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/\",\"name\":\"Fundesplai M\u00f3n Escolar\",\"description\":\"Serveis de lleure educatiu per a escoles\",\"publisher\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Fundesplai - M\u00f3n Escolar\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-mon-escolar.png\",\"contentUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-mon-escolar.png\",\"width\":468,\"height\":211,\"caption\":\"Fundesplai - M\u00f3n Escolar\"},\"image\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/fundesplai\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/76811d1ba58c8af329733060a9b10f67\",\"name\":\"cespinosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=ge19c20d194305319a8aa1f395733a37b\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g\",\"caption\":\"cespinosa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 son las Bressol de verano? - Fundesplai M\u00f3n Escolar","description":"Las Bressol de Verano son los casales de verano para la Peque\u00f1a Infancia, \u00a1permiten a los ni\u00f1os\/as de 0 a 3 disfrutar del ocio en verano!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 son las Bressol de verano? - Fundesplai M\u00f3n Escolar","og_description":"Las Bressol de Verano son los casales de verano para la Peque\u00f1a Infancia, \u00a1permiten a los ni\u00f1os\/as de 0 a 3 disfrutar del ocio en verano!","og_url":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/","og_site_name":"Fundesplai M\u00f3n Escolar","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2018-05-30T06:53:45+00:00","article_modified_time":"2023-06-16T06:56:47+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/BRESSOLS_ESTIU_Fundesplai-1.jpg","type":"image\/jpeg"}],"author":"cespinosa","twitter_card":"summary_large_image","twitter_creator":"@fundesplai","twitter_site":"@fundesplai","twitter_misc":{"Escrito por":"cespinosa","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/#article","isPartOf":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/"},"author":{"name":"cespinosa","@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/person\/76811d1ba58c8af329733060a9b10f67"},"headline":"\u00bfQu\u00e9 son las Bressol de verano?","datePublished":"2018-05-30T06:53:45+00:00","dateModified":"2023-06-16T06:56:47+00:00","mainEntityOfPage":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/"},"wordCount":929,"publisher":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/BRESSOLS_ESTIU_Fundesplai-1.jpg","keywords":["0-3","actividades","casal","casal de verano","escuela infantil","juego","peque\u00f1a infancia"],"articleSection":["Peque\u00f1a infancia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/","url":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/","name":"\u00bfQu\u00e9 son las Bressol de verano? - Fundesplai M\u00f3n Escolar","isPartOf":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/#primaryimage"},"image":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/#primaryimage"},"thumbnailUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/BRESSOLS_ESTIU_Fundesplai-1.jpg","datePublished":"2018-05-30T06:53:45+00:00","dateModified":"2023-06-16T06:56:47+00:00","description":"Las Bressol de Verano son los casales de verano para la Peque\u00f1a Infancia, \u00a1permiten a los ni\u00f1os\/as de 0 a 3 disfrutar del ocio en verano!","breadcrumb":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/#primaryimage","url":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/BRESSOLS_ESTIU_Fundesplai-1.jpg","contentUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2018\/05\/BRESSOLS_ESTIU_Fundesplai-1.jpg","width":1888,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/que-son-las-bressol-de-verano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/escoles.fundesplai.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Peque\u00f1a infancia","item":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/"},{"@type":"ListItem","position":4,"name":"\u00bfQu\u00e9 son las Bressol de verano?"}]},{"@type":"WebSite","@id":"https:\/\/escoles.fundesplai.org\/es\/#website","url":"https:\/\/escoles.fundesplai.org\/es\/","name":"Fundesplai M\u00f3n Escolar","description":"Serveis de lleure educatiu per a escoles","publisher":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escoles.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/escoles.fundesplai.org\/es\/#organization","name":"Fundesplai - M\u00f3n Escolar","url":"https:\/\/escoles.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2021\/08\/logo-mon-escolar.png","contentUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2021\/08\/logo-mon-escolar.png","width":468,"height":211,"caption":"Fundesplai - M\u00f3n Escolar"},"image":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/fundesplai","https:\/\/www.instagram.com\/fundesplai\/"]},{"@type":"Person","@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/person\/76811d1ba58c8af329733060a9b10f67","name":"cespinosa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=ge19c20d194305319a8aa1f395733a37b","url":"https:\/\/secure.gravatar.com\/avatar\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g","caption":"cespinosa"}}]}},"authors":[{"term_id":809,"user_id":3,"is_guest":0,"slug":"cespinosa","display_name":"cespinosa","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/43083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=43083"}],"version-history":[{"count":2,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/43083\/revisions"}],"predecessor-version":[{"id":43085,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/43083\/revisions\/43085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/42802"}],"wp:attachment":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=43083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=43083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=43083"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/ppma_author?post=43083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}