{"id":73496,"date":"2026-08-25T10:04:04","date_gmt":"2026-08-25T08:04:04","guid":{"rendered":"https:\/\/escoles.fundesplai.org\/sin-categorizar\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/"},"modified":"2026-09-01T11:16:51","modified_gmt":"2026-09-01T09:16:51","slug":"adaptacion-en-la-escuela-13-consejos-para-equipos-educativos","status":"publish","type":"post","link":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/","title":{"rendered":"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection INTRO\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>El inicio de la escuela es uno de los momentos m\u00e1s significativos en la vida de muchos ni\u00f1os y ni\u00f1as.<\/strong> Para muchos ni\u00f1os y ni\u00f1as representa la primera separaci\u00f3n prolongada de la familia o bien el reencuentro con la escuela despu\u00e9s de las vacaciones, un per\u00edodo en el que han estado rodeados de su entorno familiar. <strong>Esta nueva etapa representa un nuevo entorno, nuevas personas, diferentes espacios, rutinas y experiencias que habr\u00e1 que ir descubriendo de forma progresiva.<\/strong><\/p>\n<p>Para las familias este cambio se vive como una mezcla de emociones entre ilusi\u00f3n, dudas y miedos. \u00bfQu\u00e9 es el per\u00edodo de adaptaci\u00f3n? \u00bfCu\u00e1nto dura? \u00bfEs normal que el ni\u00f1o o ni\u00f1a llore? \u00bfC\u00f3mo puedo ayudarle? En este proceso de adaptaci\u00f3n, maestros, maestras, monitores y monitoras de comedor y actividades extraescolares, veladores\/as y otros referentes educativos, <strong>tenemos un papel clave en el acompa\u00f1amiento a ni\u00f1os, ni\u00f1as, o familias,<\/strong> transmitiendo confianza y orient\u00e1ndolas en este nuevo camino.     <\/p>\n<p>Desde <a href=\"https:\/\/fundesplai.org\/\">Fundesplai<\/a>, en las escuelas donde estamos presentes, tenemos muy en cuenta este per\u00edodo, porque representa el primer contacto del ni\u00f1o y ni\u00f1a con un entorno nuevo. Una adaptaci\u00f3n vivida de forma positiva contribuye al bienestar emocional del ni\u00f1o o ni\u00f1a y facilita sus futuros aprendizajes y relaciones. Por este motivo, a continuaci\u00f3n compartimos contigo algunas <strong>recomendaciones para facilitar la adaptaci\u00f3n a la escuela durante el mes de septiembre o en otros momentos de regreso de vacaciones.<\/strong>  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection: Taula continguts\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbMESA CONTENIDOS\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection: Segueix-nos\u00bb module_id=\u00bbbolet\u00edn\u00bb module_class=\u00bbseccio-segueix-nos\u00bb _builder_version=\u00bb4.27.5&#8243; custom_margin=\u00bb100px||50px||false|false\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb-200px||||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb border_color_all=\u00bb#DCDC1C\u00bb locked=\u00bboff\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.5&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb max_width=\u00bb1080px\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb border_width_all=\u00bb3px\u00bb border_color_all=\u00bb#DCDC1C\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbFormulari subscripci\u00f3 mail\u00bb _builder_version=\u00bb4.27.5&#8243; text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb10px|10px|10px|10px|false|false\u00bb border_color_all=\u00bb#DCDC1C\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\"><strong>Si te interesan los recursos educativos<\/strong>, pensados \u200b\u200bespecialmente para profesionales de la educaci\u00f3n, <strong>suscr\u00edbete a nuestro blog<\/strong> y los recibir\u00e1s cada semana en tu mail, \u00a1con gu\u00edas y materiales exclusivos para personas suscriptoras! \ud83d\ude0a<\/p>\n<p style=\"text-align: left;\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_1' ><div id='gf_1' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_1' id='gform_1'  action='\/es\/wp-json\/wp\/v2\/posts\/73496#gf_1' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_1_4\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_4'><span class='gform-field-label__text'>Comments<\/span><\/label><div class='ginput_container'><input name='input_4' id='input_1_4' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_1_4'>Este campo es un campo de validaci\u00f3n y debe quedar sin cambios.<\/div><\/li><li id=\"field_1_1\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'><span class='gform-field-label__text'>Correo electr\u00f3nico<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_1' id='input_1_1' type='email' value='' class='large'   placeholder='Tu correo electr\u00f3nico' aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_1_2\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Pol\u00edtica de confidencialidad<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_1_2'><li class='gchoice gchoice_1_2_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_2.1' type='checkbox'  value='He llegit i accepto la &lt;a href=&quot;https:\/\/escoles.fundesplai.org\/es\/politica-de-privacidad\/&quot; target=&#039;_blank&#039;&gt;pol\u00edtica de privacitat&lt;\/a&gt;'  id='choice_1_2_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_1_2_1' id='label_1_2_1' class='gform-field-label gform-field-label--type-inline'>He le\u00eddo y acepto la <a href='\/es\/politica-de-privacidad\/' target='_blank'>pol\u00edtica de privacidad<\/a><\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_1_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_hidden\"  ><div class=\"admin-hidden-markup\"><i class=\"gform-icon gform-icon--hidden\" aria-hidden=\"true\" title=\"Este campo est\u00e1 oculto cuando se visualiza el formulario\"><\/i><span>Este campo est\u00e1 oculto cuando se visualiza el formulario<\/span><\/div><label class='gfield_label gform-field-label' for='input_1_3'><span class='gform-field-label__text'>idioma<\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_1_3' type='text' value='es' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <button type='submit' id='gform_submit_button_1' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' >Suscr\u00edbete<\/button> <input type='hidden' name='gform_ajax' value='form_id=1&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=a2a0076f00a1a95197123b5f2e56bc33' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='douQrkrLjxG2KgGarS3Z1W5OYtxH1hw3RQeqSFjWoeJ4I9WDxyGaXifbnE+\/8CrzHm5okzv0hGhhaVLB9Ndt1A95173YECKvbw6a3PQTNZQyJDw=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJ7XCJnZm9ybV9zdWJtaXNzaW9uX21ldGhvZFwiOltcImZhZmVhMjM2ZTI4ZTU1YjAyZmJhNzhjYmViNjQzNWQ4XCIsXCIzOTkyODFlMDlmOTQyZDM4YjZmMDU2OTRiN2U2Nzg4M1wiLFwiZGM0Mzg3NzI2N2I3NGMxMThjOGUyYTk2YzI3OWE5NGNcIl0sXCJnZm9ybV90aGVtZVwiOlwiZTYzYjY4YTY2ODY2YjIxNDhmZGM5NjkyZDE5NTNlZWNcIixcImdmb3JtX3N0eWxlX3NldHRpbmdzXCI6XCI0NTBhM2ZjMTQ3MDg0ZmI0YmVmZGM1ZDkyY2E3ZDVmNlwiLFwiZm9ybV9pZFwiOlwiNjJiNzBkZTAwOTgxNDcxZDRkNTUwZjA0MzgxNTE0NjlcIixcInVybFwiOlwiYzE4NGJlNzU5MGJjYzU4MTFjMDlmMjFhNDAyMmI0MzRcIixcInN0YXRlX3RpbWVzdGFtcFwiOlwiYTlhMmE5OWEyM2JlNGNiOWRjMTU1MTdjNDExZGQyOWFcIn0iLCI3Mjc4ZjU2ZWEwYTBmMDQzZDE4MGZiMDAyYzM0MmVhNCIsMTc4ODM4NTMyOF0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_1' id='gform_ajax_frame_1' title='Este iframe contiene la l\u00f3gica necesaria para gestionar formularios con ajax activado.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_1').offset().top - mt); }, 50 );var current_page = jQuery('#gform_source_page_number_1').val();jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_1').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection: Cos\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbCONSEJOS PR\u00c1CTICOS PARA FAMILIAS\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px||||false|false\u00bb locked=\u00bboff\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text admin_label=\u00bbT\u00edtol\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Taula de continguts<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #525459;color:#525459\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #525459;color:#525459\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#%F0%9F%93%9D_13_Consejos_practicos_para_tener_en_cuenta_al_inicio_de_curso\" >\ud83d\udcdd 13 Consejos pr\u00e1cticos para tener en cuenta al inicio de curso<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#1_Explicar_el_proceso_de_adaptacion\" >1. Explicar el proceso de adaptaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#2_Transmitir_confianza_y_seguridad\" >2. Transmitir confianza y seguridad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#3_Mantener_una_comunicacion_fluida\" >3. Mantener una comunicaci\u00f3n fluida<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#4_Validar_las_emociones_y_crear_vinculo\" >4. Validar las emociones y crear v\u00ednculo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#5_Mantener_rutinas_estables\" >5. Mantener rutinas estables<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#6_Respetar_los_objetos_de_apego_y_los_recordatorios_dibujados\" >6. Respetar los objetos de apego y los recordatorios dibujados<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#7_Fomentar_la_autonomia_del_nino_o_nina_y_la_participacion_activa\" >7. Fomentar la autonom\u00eda del ni\u00f1o o ni\u00f1a y la participaci\u00f3n activa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#8_Crear_un_ambiente_acogedor\" >8. Crear un ambiente acogedor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#9_Favorecer_el_tiempo_para_jugar\" >9. Favorecer el tiempo para jugar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#10_Respetar_los_distintos_ritmos_de_adaptacion\" >10. Respetar los distintos ritmos de adaptaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#11_Promover_actividades_de_cohesion_de_grupo\" >11. Promover actividades de cohesi\u00f3n de grupo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#12_Definir_las_normas_de_convivencia\" >12. Definir las normas de convivencia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#13_Favorecer_las_actividades_al_aire_libre\" >13. Favorecer las actividades al aire libre<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"%F0%9F%93%9D_13_Consejos_practicos_para_tener_en_cuenta_al_inicio_de_curso\"><\/span>\ud83d\udcdd 13 Consejos pr\u00e1cticos para tener en cuenta al inicio de curso<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>[\/et_pb_text][et_pb_divider _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbRow\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bb1. Import\u00e0ncia proc\u00e9s adaptaci\u00f3\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"1_Explicar_el_proceso_de_adaptacion\"><\/span><strong>1. Explicar el proceso de adaptaci\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Es importante explicar a las familias que <strong>cada ni\u00f1o o ni\u00f1a vive la adaptaci\u00f3n de forma diferente.<\/strong> Algunos se integran r\u00e1pidamente, mientras que otros necesitan m\u00e1s tiempo para sentirse seguros. El objetivo no es conseguir una adaptaci\u00f3n r\u00e1pida, sino que sea respetuosa con las necesidades emocionales de cada ni\u00f1o o ni\u00f1a. Por este motivo, existen escuelas que organizan el per\u00edodo de adaptaci\u00f3n de manera progresiva, con el objetivo de facilitar la incorporaci\u00f3n de los ni\u00f1os y ni\u00f1as al nuevo entorno. Disponer de este conocimiento <strong>ayuda a las familias a entender qu\u00e9 puede suceder y tambi\u00e9n les permite participar y dar un mejor apoyo<\/strong> a sus hijos o hijas.   <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb2. Transmetre confian\u00e7a i seguretat\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"2_Transmitir_confianza_y_seguridad\"><\/span><strong>2. Transmitir confianza y seguridad<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Es importante transmitir a las familias la importancia de establecer una relaci\u00f3n de confianza. Por eso, como referentes educativos nos tenemos que mostrar disponibles a resolver dudas o miedos que puedan surgir durante el periodo de adaptaci\u00f3n. Tambi\u00e9n, es conveniente motivar a las familias a compartir informaci\u00f3n relevante sobre sus hijos o hijas, como por ejemplo sus necesidades, preferencias y h\u00e1bitos, por ejemplo: le encanta la m\u00fasica, disfruta dibujando, tiene intolerancia a la leche, tiene miedo de los ruidos fuertes, tiene tendencia a la timidez o es muy sociable, utiliza un objeto de aferramiento&#8230;  <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb3. Mantenir una comunicaci\u00f3 flu\u00efda\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"3_Mantener_una_comunicacion_fluida\"><\/span><strong>3. Mantener una comunicaci\u00f3n fluida<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Hablar con los ni\u00f1os y ni\u00f1as con fluidez y anticipar la informaci\u00f3n les proporciona seguridad, organizaci\u00f3n y claridad. Tambi\u00e9n ayuda a anticipar qu\u00e9 va a pasar y favorece tanto la separaci\u00f3n como el reencuentro despu\u00e9s de la escuela. Por este motivo, <strong>es recomendable explicar qu\u00e9 har\u00e1n, qui\u00e9n les acompa\u00f1ar\u00e1, qui\u00e9n ir\u00e1 a buscarlos&#8230; reduciendo as\u00ed la incertidumbre de los primeros d\u00edas.<\/strong><br \/>Tambi\u00e9n, hay que recordar la importancia de la sinceridad y la empat\u00eda con los ni\u00f1os y ni\u00f1as, tanto por parte de los equipos educativos como por las familias, evitando enga\u00f1os o sorpresas desagradables, ya que esto puede generar mayor desconfianza e inseguridad en el ni\u00f1o o ni\u00f1a, influyendo negativamente en este per\u00edodo.  <\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Infant-pare-abracats-Fundesplai.jpg\u00bb alt=\u00bbNi\u00f1o y padre abrazados Fundesplai\u00bb title_text=\u00bbNi\u00f1o padre abrazados Fundesplai\u00bb align=\u00bbcenter\u00bb admin_label=\u00bbImage (abra\u00e7ada)\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||35px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text admin_label=\u00bb4. Validar les emocions i crear vincle\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"4_Validar_las_emociones_y_crear_vinculo\"><\/span><strong>4. Validar las emociones y crear v\u00ednculo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Debemos esforzarnos en crear v\u00ednculo emocional con cada ni\u00f1o o ni\u00f1a y validar sus emociones desde la empat\u00eda y la paciencia. Tambi\u00e9n es importante explicar a las familias c\u00f3mo hacer esta validaci\u00f3n. Durante la \u00e9poca de la adaptaci\u00f3n surgen sentimientos de tristeza, miedo y a\u00f1oranza. Como referentes, en lugar de minimizarlos y juzgarlos con comentarios \u201cNo pasa nada\u201d, \u201cNo llores\u201d, etc. <strong>Es importante escuchar la emoci\u00f3n del ni\u00f1o o ni\u00f1a, reconocerla y ponerle nombre,<\/strong> dado que en estas edades todav\u00eda no disponen de recursos suficientes para identificar y expresar lo que sienten.   <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb5. Mantenir rutines estables\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"5_Mantener_rutinas_estables\"><\/span><strong>5. Mantener rutinas estables<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Es muy importante que tanto en la escuela como en casa se sigan rutinas estables, claras y previsibles como <strong>mantener horarios regulares de sue\u00f1o, comidas y actividades. Las rutinas aportan a los ni\u00f1os y ni\u00f1as estabilidad y seguridad. <\/strong> Cuando los ni\u00f1os y ni\u00f1as saben qu\u00e9 va a pasar, se sienten m\u00e1s tranquilos y confiados, ya que pueden anticipar las actividades y entender mejor su entorno, de esta manera es m\u00e1s f\u00e1cil que afronte la entrada en la escuela con m\u00e1s tranquilidad. Las rutinas tambi\u00e9n ayudan a favorecer una buena din\u00e1mica de grupo desde la diversidad de necesidades. <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb6. Respectar els objectes d&#8217;aferrament i recordatoris dibuixats\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"6_Respetar_los_objetos_de_apego_y_los_recordatorios_dibujados\"><\/span><strong>6. Respetar los objetos de apego y los recordatorios dibujados<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><strong>Hay s\u00edmbolos u objetos que pueden ayudar a los ni\u00f1os y ni\u00f1as a sentirse tranquilos a pesar de estar separados de sus familias.<\/strong> La funci\u00f3n de estos objetos de apego es que no son juguetes cualquiera, sino objetos con un gran valor afectivo que proporcionan seguridad, confort y tranquilidad al ni\u00f1o o ni\u00f1a ante situaciones nuevas o momentos de separaci\u00f3n. Algunos de estos ejemplos de estos objetos son: mantillas, peluches, dibujos en la mano&#8230; <\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Infant-objecte-aferrament-Fundesplai.jpg\u00bb alt=\u00bbInfante jugando con objeto apego Fundesplai\u00bb title_text=\u00bbInfante objeto apego Fundesplai\u00bb align=\u00bbcenter\u00bb admin_label=\u00bbImage (abra\u00e7ada)\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||35px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text admin_label=\u00bb7. Fomentar l&#8217;autonomia de l&#8217;infant i la participaci\u00f3 activa\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"7_Fomentar_la_autonomia_del_nino_o_nina_y_la_participacion_activa\"><\/span><strong>7. Fomentar la autonom\u00eda del ni\u00f1o o ni\u00f1a y la participaci\u00f3n activa<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Confiar en sus capacidades favorece su autoestima y la confianza en s\u00ed mismo, esto durante el per\u00edodo de adaptaci\u00f3n es clave. Debemos respetar el ritmo de cada ni\u00f1o o ni\u00f1a, <strong>evitando anticiparse a sus necesidades, d\u00e1ndoles tiempo y ofreci\u00e9ndoles oportunidades de autoaprendizaje en las peque\u00f1as acciones del d\u00eda a d\u00eda,<\/strong> como colgar la mochila, quitarse la chaqueta, guardar su vaso&#8230; Adem\u00e1s, favorecer la participaci\u00f3n activa ayudar\u00e1 en el proceso de adaptaci\u00f3n.  <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb8. Crear un ambient acollidor\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"8_Crear_un_ambiente_acogedor\"><\/span><strong>8. Crear un ambiente acogedor<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Prepara el aula para que sea un espacio c\u00e1lido, seguro y atractivo, con materiales accesibles y referentes visuales que ayuden a los ni\u00f1os o ni\u00f1as a orientarse, a sentirse bien ya jugar. Adem\u00e1s, es importante que las normas de uso de espacios est\u00e9n muy claras con horarios visuales, pictogramas y etiquetas identificativas. <\/p>\n<ul>\n<li><a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/apoyo-a-los-alumnos-con-nee\/como-adaptar-el-espacio-para-un-nino-con-tea\/\">C\u00f3mo adaptar el espacio para ni\u00f1os o ni\u00f1as con TEA<\/a><\/li>\n<li><a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/como-favorecer-el-juego-libre-a-traves-del-espacio\/\">Espacios educativos potenciadores de juego y bienestar<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb9. Afavorir el temps per jugar\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"9_Favorecer_el_tiempo_para_jugar\"><\/span><strong>9. Favorecer el tiempo para jugar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Durante los primeros d\u00edas es importante que promovamos ratos de juego libre, de juego dirigido en movimiento, juegos de mesa o simplemente ratos de juego en el patio que favorezcan la socializaci\u00f3n entre iguales. En este sentido, los <a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/guia-de-juegos-cooperativos-en-movimiento\/\">juegos cooperativos en movimiento<\/a> dinamizados pueden resultar muy \u00fatiles. <\/p>\n<ul>\n<li><a href=\"https:\/\/cases.fundesplai.org\/es\/blog-es\/actividades\/juegos-de-mesa-para-todos-y-todas\/\">Juegos de mesa para todos<\/a><\/li>\n<li><a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/pequena-infancia\/la-magia-del-juego-libre\/\">La magia del juego libre<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb10. Respectar els diferents ritmes d&#8217;adaptaci\u00f3\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"10_Respetar_los_distintos_ritmos_de_adaptacion\"><\/span><strong>10. Respetar los distintos ritmos de adaptaci\u00f3n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cada ni\u00f1o y ni\u00f1a vive la separaci\u00f3n y los nuevos entornos de forma diferente. Es necesario evitar comparaciones y adaptar las expectativas a las necesidades de cada uno. Tambi\u00e9n es importante transmitir esta idea a la familia para rebajar exigencias y ajustar expectativas a la realidad del momento y al ritmo y necesidad de cada ni\u00f1o o ni\u00f1a.  <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb11.Promoure activitats de cohesi\u00f3 de grup\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"11_Promover_actividades_de_cohesion_de_grupo\"><\/span><strong>11. Promover actividades de cohesi\u00f3n de grupo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Los juegos de conocimiento y presentaci\u00f3n, din\u00e1micas cooperativas y propuestas l\u00fadicas <strong>ayudan a romper el hielo, sentirse integrados, crear v\u00ednculos y ganar confianza dentro del grupo.<\/strong> Tambi\u00e9n favorecen que el inicio de curso sea m\u00e1s seguro, cercano y divertido. Estas actividades tambi\u00e9n tienen como objetivo fomentar la comunicaci\u00f3n, la participaci\u00f3n, la cooperaci\u00f3n y la escucha activa. <\/p>\n<ul>\n<li><a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/educacion-en-el-tiempo-libre\/10-juegos-de-conocimiento-para-el-inicio-de-curso\/\">20 juegos y din\u00e1micas para el inicio de curso<\/a><\/li>\n<li><a href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/educacion-en-el-tiempo-libre\/10-juegos-de-conocimiento-para-el-inicio-de-curso\/\">10 din\u00e1micas de conocimiento<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb12. Definir les normes de conviv\u00e8ncia\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"12_Definir_las_normas_de_convivencia\"><\/span><strong>12. Definir las normas de convivencia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>La definici\u00f3n de las normas y los l\u00edmites de la escuela, la relaci\u00f3n con los compa\u00f1eros y compa\u00f1eras y con el equipo educativo es esencial para una buena convivencia<\/strong> y para dar un marco de referencia claro a los ni\u00f1os y ni\u00f1as con l\u00edmites que les ayuden a crecer con autonom\u00eda y seguridad. Tambi\u00e9n es necesario transmitir muy bien estas normas y l\u00edmites a las familias para que desde casa puedan reforzar los mensajes, evitando as\u00ed posibles malentendidos. Es interesante que los ni\u00f1os y ni\u00f1as participen de forma activa en la elaboraci\u00f3n de la normativa de convivencia para favorecer un clima de cohesi\u00f3n de grupo y de respeto por las normas, compa\u00f1eros y compa\u00f1eras y equipo educativo.  <\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bb13. Afavorir les activitats a l&#8217;aire lliure\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb35px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"13_Favorecer_las_actividades_al_aire_libre\"><\/span><strong>13. Favorecer las actividades al aire libre<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Es importante aprovechar los espacios al aire libre para crear un ambiente relajado, placentero y de confianza al inicio de curso.<\/strong> Estos espacios permiten a los ni\u00f1os y ni\u00f1as conocerse mejor, relacionarse con sus compa\u00f1eros y crear nuevos v\u00ednculos a trav\u00e9s del juego, la exploraci\u00f3n y las experiencias compartidas.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||40px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cabe recordar que el proceso de adaptaci\u00f3n no depende \u00fanicamente del ni\u00f1o, sino que <strong>es un proceso compartido en el que participa toda la comunidad educativa.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbXXSS\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>Si te ha gustado esta entrada, \u00a1comp\u00e1rtela en las redes!<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El inicio de la escuela es uno de los momentos m\u00e1s significativos para la vida de los muchos ni\u00f1os y ni\u00f1as. Tambi\u00e9n, para las familias, se vive como una mezcla de emociones. \u00bfQu\u00e9 es el periodo de adaptaci\u00f3n? \u00bfCu\u00e1nto dura? ?C\u00f3mo puedo ayudarlo?    <\/p>\n","protected":false},"author":41,"featured_media":73307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[272],"tags":[],"ppma_author":[806],"class_list":["post-73496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos - Fundesplai M\u00f3n Escolar<\/title>\n<meta name=\"description\" content=\"El inicio de la escuela es uno de los momentos m\u00e1s significativos para muchos ni\u00f1os. Para las familias se vive tambi\u00e9n como una mezcla de emociones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos - Fundesplai M\u00f3n Escolar\" \/>\n<meta property=\"og:description\" content=\"El inicio de la escuela es uno de los momentos m\u00e1s significativos para muchos ni\u00f1os. Para las familias se vive tambi\u00e9n como una mezcla de emociones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundesplai M\u00f3n Escolar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-25T08:04:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:16:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Mans-infant-petita-infancia-Fundesplai-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina L\u00f3pez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fundesplai\" \/>\n<meta name=\"twitter:site\" content=\"@fundesplai\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristina L\u00f3pez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/\"},\"author\":{\"name\":\"Cristina L\u00f3pez\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/3aa237f49afe8ec76709a5845245ea22\"},\"headline\":\"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos\",\"datePublished\":\"2026-08-25T08:04:04+00:00\",\"dateModified\":\"2026-09-01T09:16:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/\"},\"wordCount\":2797,\"publisher\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Mans-infant-petita-infancia-Fundesplai-2.jpg\",\"articleSection\":[\"Recursos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/\",\"name\":\"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos - Fundesplai M\u00f3n Escolar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Mans-infant-petita-infancia-Fundesplai-2.jpg\",\"datePublished\":\"2026-08-25T08:04:04+00:00\",\"dateModified\":\"2026-09-01T09:16:51+00:00\",\"description\":\"El inicio de la escuela es uno de los momentos m\u00e1s significativos para muchos ni\u00f1os. Para las familias se vive tambi\u00e9n como una mezcla de emociones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Mans-infant-petita-infancia-Fundesplai-2.jpg\",\"contentUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Mans-infant-petita-infancia-Fundesplai-2.jpg\",\"width\":1888,\"height\":900,\"caption\":\"Manos infante peque\u00f1a infancia sobre caja Fundesplai\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recursos\",\"item\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/blog-es\\\/recursos-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/\",\"name\":\"Fundesplai M\u00f3n Escolar\",\"description\":\"Serveis de lleure educatiu per a escoles\",\"publisher\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Fundesplai - M\u00f3n Escolar\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-mon-escolar.png\",\"contentUrl\":\"https:\\\/\\\/escoles.fundesplai.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-mon-escolar.png\",\"width\":468,\"height\":211,\"caption\":\"Fundesplai - M\u00f3n Escolar\"},\"image\":{\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/fundesplai\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/3aa237f49afe8ec76709a5845245ea22\",\"name\":\"Cristina L\u00f3pez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5af99f749e8a89e28f5626cf47be89de83cd581b608c2f51e6205efdbe4ac859?s=96&d=mm&r=g33b10c3842784c7d692cb02f19881cec\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5af99f749e8a89e28f5626cf47be89de83cd581b608c2f51e6205efdbe4ac859?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5af99f749e8a89e28f5626cf47be89de83cd581b608c2f51e6205efdbe4ac859?s=96&d=mm&r=g\",\"caption\":\"Cristina L\u00f3pez\"},\"description\":\"Mestra compromesa amb l'educaci\u00f3 i especialitzada en la creaci\u00f3 de continguts educatius. Dissenyo recursos, idees i propostes amb creativitat, rigor pedag\u00f2gic i una mirada pr\u00e0ctica, aportant valor als equips educatius.\",\"url\":\"https:\\\/\\\/escoles.fundesplai.org\\\/es\\\/author\\\/cristina-lopez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos - Fundesplai M\u00f3n Escolar","description":"El inicio de la escuela es uno de los momentos m\u00e1s significativos para muchos ni\u00f1os. Para las familias se vive tambi\u00e9n como una mezcla de emociones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/","og_locale":"es_ES","og_type":"article","og_title":"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos - Fundesplai M\u00f3n Escolar","og_description":"El inicio de la escuela es uno de los momentos m\u00e1s significativos para muchos ni\u00f1os. Para las familias se vive tambi\u00e9n como una mezcla de emociones.","og_url":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/","og_site_name":"Fundesplai M\u00f3n Escolar","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2026-08-25T08:04:04+00:00","article_modified_time":"2026-09-01T09:16:51+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Mans-infant-petita-infancia-Fundesplai-2.jpg","type":"image\/jpeg"}],"author":"Cristina L\u00f3pez","twitter_card":"summary_large_image","twitter_creator":"@fundesplai","twitter_site":"@fundesplai","twitter_misc":{"Escrito por":"Cristina L\u00f3pez","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#article","isPartOf":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/"},"author":{"name":"Cristina L\u00f3pez","@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/person\/3aa237f49afe8ec76709a5845245ea22"},"headline":"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos","datePublished":"2026-08-25T08:04:04+00:00","dateModified":"2026-09-01T09:16:51+00:00","mainEntityOfPage":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/"},"wordCount":2797,"publisher":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#primaryimage"},"thumbnailUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Mans-infant-petita-infancia-Fundesplai-2.jpg","articleSection":["Recursos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/","url":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/","name":"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos - Fundesplai M\u00f3n Escolar","isPartOf":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#primaryimage"},"image":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#primaryimage"},"thumbnailUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Mans-infant-petita-infancia-Fundesplai-2.jpg","datePublished":"2026-08-25T08:04:04+00:00","dateModified":"2026-09-01T09:16:51+00:00","description":"El inicio de la escuela es uno de los momentos m\u00e1s significativos para muchos ni\u00f1os. Para las familias se vive tambi\u00e9n como una mezcla de emociones.","breadcrumb":{"@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#primaryimage","url":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Mans-infant-petita-infancia-Fundesplai-2.jpg","contentUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2026\/07\/Mans-infant-petita-infancia-Fundesplai-2.jpg","width":1888,"height":900,"caption":"Manos infante peque\u00f1a infancia sobre caja Fundesplai"},{"@type":"BreadcrumbList","@id":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/adaptacion-en-la-escuela-13-consejos-para-equipos-educativos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/escoles.fundesplai.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Recursos","item":"https:\/\/escoles.fundesplai.org\/es\/blog-es\/recursos-es\/"},{"@type":"ListItem","position":4,"name":"Adaptaci\u00f3n en la escuela: 13 consejos para equipos educativos"}]},{"@type":"WebSite","@id":"https:\/\/escoles.fundesplai.org\/es\/#website","url":"https:\/\/escoles.fundesplai.org\/es\/","name":"Fundesplai M\u00f3n Escolar","description":"Serveis de lleure educatiu per a escoles","publisher":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escoles.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/escoles.fundesplai.org\/es\/#organization","name":"Fundesplai - M\u00f3n Escolar","url":"https:\/\/escoles.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2021\/08\/logo-mon-escolar.png","contentUrl":"https:\/\/escoles.fundesplai.org\/wp-content\/uploads\/2021\/08\/logo-mon-escolar.png","width":468,"height":211,"caption":"Fundesplai - M\u00f3n Escolar"},"image":{"@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/fundesplai","https:\/\/www.instagram.com\/fundesplai\/"]},{"@type":"Person","@id":"https:\/\/escoles.fundesplai.org\/es\/#\/schema\/person\/3aa237f49afe8ec76709a5845245ea22","name":"Cristina L\u00f3pez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5af99f749e8a89e28f5626cf47be89de83cd581b608c2f51e6205efdbe4ac859?s=96&d=mm&r=g33b10c3842784c7d692cb02f19881cec","url":"https:\/\/secure.gravatar.com\/avatar\/5af99f749e8a89e28f5626cf47be89de83cd581b608c2f51e6205efdbe4ac859?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5af99f749e8a89e28f5626cf47be89de83cd581b608c2f51e6205efdbe4ac859?s=96&d=mm&r=g","caption":"Cristina L\u00f3pez"},"description":"Mestra compromesa amb l'educaci\u00f3 i especialitzada en la creaci\u00f3 de continguts educatius. Dissenyo recursos, idees i propostes amb creativitat, rigor pedag\u00f2gic i una mirada pr\u00e0ctica, aportant valor als equips educatius.","url":"https:\/\/escoles.fundesplai.org\/es\/author\/cristina-lopez\/"}]}},"authors":[{"term_id":806,"user_id":41,"is_guest":0,"slug":"cristina-lopez","display_name":"Cristina L\u00f3pez","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/5af99f749e8a89e28f5626cf47be89de83cd581b608c2f51e6205efdbe4ac859?s=96&d=mm&r=g","author_category":"1","first_name":"Cristina","last_name":"L\u00f3pez","user_url":"","job_title":"Especialista en redacci\u00f3","description":"Mestra compromesa amb l'educaci\u00f3 i especialitzada en la creaci\u00f3 de continguts\r\neducatius. Dissenyo recursos, idees i propostes amb creativitat, rigor pedag\u00f2gic\r\ni una mirada pr\u00e0ctica, aportant valor als equips educatius."}],"_links":{"self":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/73496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=73496"}],"version-history":[{"count":4,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/73496\/revisions"}],"predecessor-version":[{"id":73505,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/73496\/revisions\/73505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/73307"}],"wp:attachment":[{"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=73496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=73496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=73496"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/escoles.fundesplai.org\/es\/wp-json\/wp\/v2\/ppma_author?post=73496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}